{"id":7216,"date":"2017-09-28T16:41:38","date_gmt":"2017-09-28T14:41:38","guid":{"rendered":"https:\/\/archiv-heilpaedagogik.de\/archiv-nach-umbau-copy\/"},"modified":"2018-06-07T10:26:16","modified_gmt":"2018-06-07T08:26:16","slug":"galerie_projekttage","status":"publish","type":"post","link":"https:\/\/archiv-heilpaedagogik.de\/pl\/galerie_projekttage\/","title":{"rendered":"Projekttage"},"content":{"rendered":"<p>Eine Bilderreihe zu den bisher stattgefundenen Projekttagen.<!--more--><\/p>\n<p>&nbsp;<\/p>\n<div class=\"om-inline-gallery-wrapper\"><div class=\"gallery-sliced gallery-with-captions\"><div class=\"gallery-sliced-box-row gallery-sliced-box-5\"><div class=\"img-box img-1\"><div class=\"hover-image-extra single-link\"><span class=\"back\"><img loading=\"lazy\" decoding=\"async\" width=\"379\" height=\"252\" src=\"https:\/\/archiv-heilpaedagogik.de\/wp-content\/themes\/beep\/img\/e.png\" data-original=\"https:\/\/archiv-heilpaedagogik.de\/wp-content\/uploads\/2018\/03\/Studierende-der-EVH-Bochum-3-379x252.jpg\" alt=\"Studierende der EVH-Bochum\" class=\"lazyload\" \/><span class=\"item-caption\">Studierende der EVH-Bochum<\/span><\/span><span class=\"over\"><a href=\"https:\/\/archiv-heilpaedagogik.de\/wp-content\/uploads\/2018\/03\/Studierende-der-EVH-Bochum-3.jpg\" class=\"link-zoom\" rel=\"prettyPhoto[postgal_427319566]\"><\/a><\/span><\/div><\/div><div class=\"img-box img-2\"><div class=\"hover-image-extra single-link\"><span class=\"back\"><img loading=\"lazy\" decoding=\"async\" width=\"379\" height=\"252\" src=\"https:\/\/archiv-heilpaedagogik.de\/wp-content\/themes\/beep\/img\/e.png\" data-original=\"https:\/\/archiv-heilpaedagogik.de\/wp-content\/uploads\/2018\/03\/Studierende-der-EVH-Bochum-2-379x252.jpg\" alt=\"Studierende der EVH-Bochum\" class=\"lazyload\" \/><span class=\"item-caption\">Studierende der EVH-Bochum<\/span><\/span><span class=\"over\"><a href=\"https:\/\/archiv-heilpaedagogik.de\/wp-content\/uploads\/2018\/03\/Studierende-der-EVH-Bochum-2.jpg\" class=\"link-zoom\" rel=\"prettyPhoto[postgal_427319566]\"><\/a><\/span><\/div><\/div><div class=\"img-box img-3\"><div class=\"hover-image-extra single-link\"><span class=\"back\"><img loading=\"lazy\" decoding=\"async\" width=\"379\" height=\"252\" src=\"https:\/\/archiv-heilpaedagogik.de\/wp-content\/themes\/beep\/img\/e.png\" data-original=\"https:\/\/archiv-heilpaedagogik.de\/wp-content\/uploads\/2018\/03\/Studierende-der-EVH-Bochum-379x252.jpg\" alt=\"Studierende der EVH-Bochum\" class=\"lazyload\" \/><span class=\"item-caption\">Studierende der EVH-Bochum<\/span><\/span><span class=\"over\"><a href=\"https:\/\/archiv-heilpaedagogik.de\/wp-content\/uploads\/2018\/03\/Studierende-der-EVH-Bochum.jpg\" class=\"link-zoom\" rel=\"prettyPhoto[postgal_427319566]\"><\/a><\/span><\/div><\/div><div class=\"clear\"><\/div><div class=\"img-box img-4\"><div class=\"hover-image-extra single-link\"><span class=\"back\"><img loading=\"lazy\" decoding=\"async\" width=\"534\" height=\"382\" src=\"https:\/\/archiv-heilpaedagogik.de\/wp-content\/themes\/beep\/img\/e.png\" data-original=\"https:\/\/archiv-heilpaedagogik.de\/wp-content\/uploads\/2018\/03\/Studierende-der-EVH-N\u00fcrnberg2-534x382.jpg\" alt=\"Studierende der EVH N\u00fcrnberg\" class=\"lazyload\" \/><span class=\"item-caption\">Studierende der EVH N\u00fcrnberg<\/span><\/span><span class=\"over\"><a href=\"https:\/\/archiv-heilpaedagogik.de\/wp-content\/uploads\/2018\/03\/Studierende-der-EVH-N\u00fcrnberg2.jpg\" class=\"link-zoom\" rel=\"prettyPhoto[postgal_427319566]\"><\/a><\/span><\/div><\/div><div class=\"img-box img-5\"><div class=\"hover-image-extra single-link\"><span class=\"back\"><img loading=\"lazy\" decoding=\"async\" width=\"574\" height=\"382\" src=\"https:\/\/archiv-heilpaedagogik.de\/wp-content\/themes\/beep\/img\/e.png\" data-original=\"https:\/\/archiv-heilpaedagogik.de\/wp-content\/uploads\/2018\/03\/Studierende-der-EVH-N\u00fcrnberg1-574x382.jpg\" alt=\"Studierende der EVH N\u00fcrnberg\" class=\"lazyload\" \/><span class=\"item-caption\">Studierende der EVH N\u00fcrnberg<\/span><\/span><span class=\"over\"><a href=\"https:\/\/archiv-heilpaedagogik.de\/wp-content\/uploads\/2018\/03\/Studierende-der-EVH-N\u00fcrnberg1.jpg\" class=\"link-zoom\" rel=\"prettyPhoto[postgal_427319566]\"><\/a><\/span><\/div><\/div><div class=\"clear\"><\/div><\/div><div class=\"gallery-sliced-box-row gallery-sliced-box-2\"><div class=\"img-box img-1\"><div class=\"hover-image-extra single-link\"><span class=\"back\"><img loading=\"lazy\" decoding=\"async\" width=\"383\" height=\"510\" src=\"https:\/\/archiv-heilpaedagogik.de\/wp-content\/themes\/beep\/img\/e.png\" data-original=\"https:\/\/archiv-heilpaedagogik.de\/wp-content\/uploads\/2018\/03\/Studierende-der-EVH-N\u00fcrnberg-383x510.jpg\" alt=\"Studierende der EVH N\u00fcrnberg\" class=\"lazyload\" \/><span class=\"item-caption\">Studierende der EVH N\u00fcrnberg<\/span><\/span><span class=\"over\"><a href=\"https:\/\/archiv-heilpaedagogik.de\/wp-content\/uploads\/2018\/03\/Studierende-der-EVH-N\u00fcrnberg.jpg\" class=\"link-zoom\" rel=\"prettyPhoto[postgal_427319566]\"><\/a><\/span><\/div><\/div><div class=\"img-box img-2\"><div class=\"hover-image-extra single-link\"><span class=\"back\"><img loading=\"lazy\" decoding=\"async\" width=\"766\" height=\"510\" src=\"https:\/\/archiv-heilpaedagogik.de\/wp-content\/themes\/beep\/img\/e.png\" data-original=\"https:\/\/archiv-heilpaedagogik.de\/wp-content\/uploads\/2018\/03\/IMG_3910-766x510.jpg\" alt=\"Studierende im Archiv\" class=\"lazyload\" \/><span class=\"item-caption\">Studierende im Archiv<\/span><\/span><span class=\"over\"><a href=\"https:\/\/archiv-heilpaedagogik.de\/wp-content\/uploads\/2018\/03\/IMG_3910.jpg\" class=\"link-zoom\" rel=\"prettyPhoto[postgal_427319566]\"><\/a><\/span><\/div><\/div><div class=\"clear\"><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Eine Bilderreihe zu den bisher stattgefundenen Projekttagen.<\/p>\n","protected":false},"author":1,"featured_media":7219,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[47,48,61],"class_list":["post-7216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-galerie","tag-archiv","tag-galerie","tag-projekttage"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/archiv-heilpaedagogik.de\/pl\/wp-json\/wp\/v2\/posts\/7216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archiv-heilpaedagogik.de\/pl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archiv-heilpaedagogik.de\/pl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archiv-heilpaedagogik.de\/pl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archiv-heilpaedagogik.de\/pl\/wp-json\/wp\/v2\/comments?post=7216"}],"version-history":[{"count":0,"href":"https:\/\/archiv-heilpaedagogik.de\/pl\/wp-json\/wp\/v2\/posts\/7216\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archiv-heilpaedagogik.de\/pl\/wp-json\/wp\/v2\/media\/7219"}],"wp:attachment":[{"href":"https:\/\/archiv-heilpaedagogik.de\/pl\/wp-json\/wp\/v2\/media?parent=7216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archiv-heilpaedagogik.de\/pl\/wp-json\/wp\/v2\/categories?post=7216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archiv-heilpaedagogik.de\/pl\/wp-json\/wp\/v2\/tags?post=7216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}